  {"id":1232,"date":"2016-05-20T09:24:01","date_gmt":"2016-05-20T13:24:01","guid":{"rendered":"https:\/\/carleton.ca\/heritage-conservation-symposium\/?page_id=1232"},"modified":"2016-05-20T09:30:28","modified_gmt":"2016-05-20T13:30:28","slug":"poster","status":"publish","type":"page","link":"https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/2016-2\/poster\/","title":{"rendered":"Poster"},"content":{"rendered":"<p><a href=\"https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-content\/uploads\/Not-my-Heritage-2016.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-1106\" src=\"https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-content\/uploads\/Not-my-Heritage-2016.jpg\" alt=\"Not my Heritage 2016\" width=\"792\" height=\"1224\" srcset=\"https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-content\/uploads\/Not-my-Heritage-2016.jpg 792w, https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-content\/uploads\/Not-my-Heritage-2016-160x247.jpg 160w, https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-content\/uploads\/Not-my-Heritage-2016-240x371.jpg 240w, https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-content\/uploads\/Not-my-Heritage-2016-768x1187.jpg 768w, https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-content\/uploads\/Not-my-Heritage-2016-400x618.jpg 400w, https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-content\/uploads\/Not-my-Heritage-2016-360x556.jpg 360w\" sizes=\"(max-width: 792px) 100vw, 792px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":16,"featured_media":0,"parent":1000,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Poster - Heritage Conservation Symposium<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/2016-2\/poster\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/2016-2\/poster\/\",\"url\":\"https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/2016-2\/poster\/\",\"name\":\"Poster - Heritage Conservation Symposium\",\"isPartOf\":{\"@id\":\"https:\/\/carleton.ca\/heritage-conservation-symposium\/#website\"},\"datePublished\":\"2016-05-20T13:24:01+00:00\",\"dateModified\":\"2016-05-20T13:30:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/2016-2\/poster\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/2016-2\/poster\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/2016-2\/poster\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/carleton.ca\/heritage-conservation-symposium\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Previous Editions\",\"item\":\"https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"2016\",\"item\":\"https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/2016-2\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Poster\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/carleton.ca\/heritage-conservation-symposium\/#website\",\"url\":\"https:\/\/carleton.ca\/heritage-conservation-symposium\/\",\"name\":\"Heritage Conservation Symposium\",\"description\":\"ÐÓ°ÉÔ­´´ University\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/carleton.ca\/heritage-conservation-symposium\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Poster - Heritage Conservation Symposium","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/2016-2\/poster\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/2016-2\/poster\/","url":"https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/2016-2\/poster\/","name":"Poster - Heritage Conservation Symposium","isPartOf":{"@id":"https:\/\/carleton.ca\/heritage-conservation-symposium\/#website"},"datePublished":"2016-05-20T13:24:01+00:00","dateModified":"2016-05-20T13:30:28+00:00","breadcrumb":{"@id":"https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/2016-2\/poster\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/2016-2\/poster\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/2016-2\/poster\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/carleton.ca\/heritage-conservation-symposium\/"},{"@type":"ListItem","position":2,"name":"Previous Editions","item":"https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/"},{"@type":"ListItem","position":3,"name":"2016","item":"https:\/\/carleton.ca\/heritage-conservation-symposium\/previous-editions\/2016-2\/"},{"@type":"ListItem","position":4,"name":"Poster"}]},{"@type":"WebSite","@id":"https:\/\/carleton.ca\/heritage-conservation-symposium\/#website","url":"https:\/\/carleton.ca\/heritage-conservation-symposium\/","name":"Heritage Conservation Symposium","description":"ÐÓ°ÉÔ­´´ University","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/carleton.ca\/heritage-conservation-symposium\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"acf":{"banner_image_type":"none"},"_links":{"self":[{"href":"https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-json\/wp\/v2\/pages\/1232"}],"collection":[{"href":"https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-json\/wp\/v2\/comments?post=1232"}],"version-history":[{"count":3,"href":"https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-json\/wp\/v2\/pages\/1232\/revisions"}],"predecessor-version":[{"id":1240,"href":"https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-json\/wp\/v2\/pages\/1232\/revisions\/1240"}],"up":[{"embeddable":true,"href":"https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-json\/wp\/v2\/pages\/1000"}],"wp:attachment":[{"href":"https:\/\/carleton.ca\/heritage-conservation-symposium\/wp-json\/wp\/v2\/media?parent=1232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}