  {"id":6731,"date":"2026-03-11T09:08:42","date_gmt":"2026-03-11T13:08:42","guid":{"rendered":"https:\/\/carleton.ca\/equity\/?post_type=cu_people&#038;p=6731"},"modified":"2026-03-11T09:08:43","modified_gmt":"2026-03-11T13:08:43","slug":"gervan-fearon-2","status":"publish","type":"cu_people","link":"https:\/\/carleton.ca\/equity\/people\/gervan-fearon-2\/","title":{"rendered":"Gervan  Fearon"},"content":{"rendered":"<header class=\"mb-6 cu-pageheader cu-component-updated md:mb-12\">\n    <h1 class=\"cu-prose-first-last font-semibold !mt-2 mb-4 md:mb-6 text-3xl md:text-4xl lg:text-5xl lg:leading-[3.5rem] relative after:absolute after:h-px after:bottom-0 pb-5 after:w-10 after:bg-cu-red after:left-px\">\n                    \n             \n                \n            <\/h1>\n\n    \n    <\/header>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Le Dr&nbsp;Gervan Fearon est recteur de la Polytechnique George Brown; pr\u00e9alablement, il a aussi occup\u00e9 cette fonction \u00e0 l\u2019Universit\u00e9 Brock et \u00e0 l\u2019Universit\u00e9 de Brandon.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avant de bifurquer vers le monde universitaire, il a travaill\u00e9 au minist\u00e8re des Finances (Conseil du Tr\u00e9sor) et au minist\u00e8re de l\u2019Agriculture, de l\u2019Alimentation et des Affaires rurales et Bureau du sous-ministre) de l\u2019Ontario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au sein du secteur priv\u00e9, le Dr Fearon a travaill\u00e9 \u00e0 Chase Econometrics, une division de la Chase Manhattan Bank. Il si\u00e8ge actuellement \u00e0 divers conseils d\u2019administration, notamment ceux du Centre d\u2019innovation de l\u2019Ontario, d\u2019Ingenium (une soci\u00e9t\u00e9 d\u2019\u00c9tat qui supervise trois mus\u00e9es nationaux), du Mus\u00e9e royal de l\u2019Ontario (ROM) et de Coll\u00e8ges Ontario. Il a pr\u00e9c\u00e9demment si\u00e9g\u00e9, entre autres, \u00e0 ceux de la Chambre de commerce de l\u2019Ontario, de Sant\u00e9 Niagara, de United Way Niagara et du Conseil des universit\u00e9s de l\u2019Ontario, ainsi qu\u2019au Brandon Urban Aboriginal Peoples\u2019 Council. Il a cofond\u00e9 le Canada Caribbean Institute en collaboration avec Sir Hilary Beckles, vice-chancelier de l\u2019Universit\u00e9 des Indes occidentales, et assur\u00e9 la pr\u00e9sidence du conseil d\u2019administration de la Tropicana Community Services Organization. Il a par ailleurs aussi pr\u00e9sid\u00e9 le groupe de r\u00e9f\u00e9rence externe pour l\u2019Initiative Appuyer les communaut\u00e9s noires du Canada (gouvernement du Canada), mise sur pied dans le contexte de la D\u00e9cennie internationale des personnes d\u2019ascendance africaine d\u00e9cr\u00e9t\u00e9e par les Nations Unies. Enfin, il a \u00e9t\u00e9 pr\u00e9sident d\u2019honneur de l\u2019\u00e9dition&nbsp;2025 du \u00ab&nbsp;Walk the Path Walkathon&nbsp;\u00bb, un \u00e9v\u00e9nement organis\u00e9 par la Walnut Foundation pour promouvoir la lutte et les traitement contre le cancer de la prostate.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Dr Fearon a \u00e9t\u00e9 fait membre de l\u2019Ordre de l\u2019Ontario en 2023; il a \u00e9galement re\u00e7u le Prix des 25&nbsp;grands immigrants du Canada de 2024, les m\u00e9dailles du jubil\u00e9 de diamant et de platine de la reine Elizabeth&nbsp;II, le Prix de l\u2019influenceur de la Fondation Micha\u00eblle Jean et le Prix humanitaire de la Journ\u00e9e Bob Marley (Ville de Toronto), entre autres distinctions. Titulaire d\u2019un doctorat en \u00e9conomie de l\u2019Universit\u00e9 Western ainsi que d\u2019une ma\u00eetrise et d\u2019un baccalaur\u00e9at \u00e8s sciences en \u00e9conomie agricole de l\u2019Universit\u00e9 de Guelph, il est comptable professionnel agr\u00e9\u00e9 (CPA et CGA), en plus de d\u00e9tenir le titre d\u2019IAS.A. de l\u2019Institut des administrateurs de soci\u00e9t\u00e9s.<\/p>\n","protected":false},"author":73,"featured_media":6704,"template":"","meta":{"_acf_changed":false,"cu_people_first_name":"Gervan ","cu_people_last_name":"Fearon","cu_people_initials":"GF","footnotes":"","_links_to":"","_links_to_target":""},"cu_people_type":[],"cu_people_expertise":[],"class_list":["post-6731","cu_people","type-cu_people","status-publish","has-post-thumbnail","hentry"],"acf":{"cu_people_job_title":"Recteur de la Polytechnique George Brown","cu_people_degree":"","cu_building":"","cu_people_office_num":"","cu_people_pronoun":"","cu_people_designation":"","cu_people_email":"","cu_people_phone":"","cu_people_phone_ext":"","cu_people_linkedin":"","cu_people_bluesky":"","cu_people_twitter":"","cu_people_instagram":"","cu_people_facebook":"","cu_people_website":"","cu_people_orcid":""},"_links":{"self":[{"href":"https:\/\/carleton.ca\/equity\/wp-json\/wp\/v2\/cu_people\/6731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carleton.ca\/equity\/wp-json\/wp\/v2\/cu_people"}],"about":[{"href":"https:\/\/carleton.ca\/equity\/wp-json\/wp\/v2\/types\/cu_people"}],"author":[{"embeddable":true,"href":"https:\/\/carleton.ca\/equity\/wp-json\/wp\/v2\/users\/73"}],"version-history":[{"count":1,"href":"https:\/\/carleton.ca\/equity\/wp-json\/wp\/v2\/cu_people\/6731\/revisions"}],"predecessor-version":[{"id":6732,"href":"https:\/\/carleton.ca\/equity\/wp-json\/wp\/v2\/cu_people\/6731\/revisions\/6732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carleton.ca\/equity\/wp-json\/wp\/v2\/media\/6704"}],"wp:attachment":[{"href":"https:\/\/carleton.ca\/equity\/wp-json\/wp\/v2\/media?parent=6731"}],"wp:term":[{"taxonomy":"cu_people_type","embeddable":true,"href":"https:\/\/carleton.ca\/equity\/wp-json\/wp\/v2\/cu_people_type?post=6731"},{"taxonomy":"cu_people_expertise","embeddable":true,"href":"https:\/\/carleton.ca\/equity\/wp-json\/wp\/v2\/cu_people_expertise?post=6731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}